{"id":13,"count":4,"description":"","link":"https:\/\/ecoledelacroiseedeschemins.fr\/en\/category\/positions\/","name":"Positions","slug":"positions","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/ecoledelacroiseedeschemins.fr\/en\/wp-json\/wp\/v2\/categories\/13"}],"collection":[{"href":"https:\/\/ecoledelacroiseedeschemins.fr\/en\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/ecoledelacroiseedeschemins.fr\/en\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/ecoledelacroiseedeschemins.fr\/en\/wp-json\/wp\/v2\/posts?categories=13"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}