{"id":2595,"date":"2015-04-28T12:19:07","date_gmt":"2015-04-28T10:19:07","guid":{"rendered":"http:\/\/ecoledelacroiseedeschemins.fr\/?p=2595"},"modified":"2015-06-23T17:08:12","modified_gmt":"2015-06-23T15:08:12","slug":"notre-participation-au-printemps-de-leducation","status":"publish","type":"post","link":"https:\/\/ecoledelacroiseedeschemins.fr\/en\/notre-participation-au-printemps-de-leducation\/","title":{"rendered":"Notre participation au Printemps de l\u2019\u00c9ducation"},"content":{"rendered":"<p><strong>L\u2019\u00e9quipe du Printemps de l\u2019\u00c9ducation a invit\u00e9 l&#8217;\u00c9cole de la Crois\u00e9e des Chemins \u00e0 l&#8217;automne 2014, \u00e0 se joindre \u00e0 sa d\u00e9marche de cr\u00e9er un r\u00e9seau de partenaires porteurs de pratiques innovantes en \u00e9ducation.<\/strong><\/p>\n<p>Fleur Mathet-Jolly a ainsi particip\u00e9 \u00e0 plusieurs rencontres et\u00a0 \u00e0 la r\u00e9daction d&#8217;un texte commun : &#8220;Ce qui nous r\u00e9unit&#8221;. Cette d\u00e9marche historique f\u00e9d\u00e9rant des acteurs d&#8217;\u00e9coles publiques et priv\u00e9es, de l&#8217;\u00e9ducation populaire, repr\u00e9sentatifs de diff\u00e9rents courants p\u00e9dagogiques, a \u00e9t\u00e9 c\u00e9l\u00e9br\u00e9e dans la joie lors des premi\u00e8res rencontres nationales du Printemps de l\u2019\u00c9ducation, les 21 et 22 mars.<\/p>\n<p>Vous n&#8217;y \u00e9tiez pas ? Vous pouvez malgr\u00e9 tout partager ce tr\u00e8s beau moment en regardant la vid\u00e9o ou en lisant le texte de ce <a href=\"http:\/\/www.printemps-education.org\/discours-collectif-ce-qui-nous-reunit\/\" target=\"_blank\">discours collectif<\/a>.<\/p>\n<p><iframe loading=\"lazy\" width=\"604\" height=\"340\" src=\"http:\/\/www.youtube.com\/embed\/bmTTVWymDf0?feature=oembed\" frameborder=\"0\" allowfullscreen><\/iframe><\/p>\n<p><strong>Le Printemps de l\u2019\u00c9ducation<\/strong> est un <a href=\"http:\/\/www.printemps-education.org\/le-printemps\/qui-sommes-nous\/\" target=\"_blank\">mouvement associatif<\/a> national, cr\u00e9\u00e9 en 2012, qui a<\/p>\n<blockquote><p>pour ambition de remettre l\u2019enfant au c\u0153ur de l\u2019\u00e9ducation et de contribuer \u00e0 rendre les enfants heureux.<br \/>\nSa vision se base sur le constat qu\u2019il est grand temps de permettre aux enfants d\u2019apprendre dans la joie, la cr\u00e9ativit\u00e9, l\u2019autonomie, le respect, la coop\u00e9ration, la paix et en lien avec la nature et le vivant, afin qu\u2019ils deviennent citoyens du monde.<\/p>\n<p>Sa mission est notamment de cr\u00e9er un r\u00e9seau d\u2019acteurs du renouveau \u00e9ducatif, de rendre visibles et de partager les pratiques p\u00e9dagogiques innovantes par l\u2019organisation de rencontres et la mise \u00e0 disposition de services, et de changer les politiques \u00e9ducatives.<\/p>\n<p>Car construire une soci\u00e9t\u00e9 plus humaniste, plus \u00e9cologique, plus solidaire est un imp\u00e9ratif qui commence par l\u2019\u00e9ducation, tant \u00e0 l\u2019\u00e9cole qu\u2019en dehors de l\u2019\u00e9cole. &#8220;<\/p><\/blockquote>\n","protected":false},"excerpt":{"rendered":"<p>L\u2019\u00e9quipe du Printemps de l\u2019\u00c9ducation a invit\u00e9 l&#8217;\u00c9cole de la Crois\u00e9e des Chemins \u00e0 l&#8217;automne 2014, \u00e0 se joindre \u00e0 sa d\u00e9marche de cr\u00e9er un r\u00e9seau de partenaires porteurs de pratiques innovantes en \u00e9ducation. Fleur Mathet-Jolly a ainsi particip\u00e9 \u00e0 plusieurs rencontres et\u00a0 \u00e0 la r\u00e9daction d&#8217;un texte commun : &#8220;Ce qui nous r\u00e9unit&#8221;. Cette &hellip; <a href=\"https:\/\/ecoledelacroiseedeschemins.fr\/en\/notre-participation-au-printemps-de-leducation\/\" class=\"more-link\">Continue reading <span class=\"screen-reader-text\">Notre participation au Printemps de l\u2019\u00c9ducation<\/span> <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":14,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0},"categories":[11],"tags":[],"_links":{"self":[{"href":"https:\/\/ecoledelacroiseedeschemins.fr\/en\/wp-json\/wp\/v2\/posts\/2595"}],"collection":[{"href":"https:\/\/ecoledelacroiseedeschemins.fr\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ecoledelacroiseedeschemins.fr\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ecoledelacroiseedeschemins.fr\/en\/wp-json\/wp\/v2\/users\/14"}],"replies":[{"embeddable":true,"href":"https:\/\/ecoledelacroiseedeschemins.fr\/en\/wp-json\/wp\/v2\/comments?post=2595"}],"version-history":[{"count":0,"href":"https:\/\/ecoledelacroiseedeschemins.fr\/en\/wp-json\/wp\/v2\/posts\/2595\/revisions"}],"wp:attachment":[{"href":"https:\/\/ecoledelacroiseedeschemins.fr\/en\/wp-json\/wp\/v2\/media?parent=2595"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ecoledelacroiseedeschemins.fr\/en\/wp-json\/wp\/v2\/categories?post=2595"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ecoledelacroiseedeschemins.fr\/en\/wp-json\/wp\/v2\/tags?post=2595"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}